{"id":7675,"date":"2011-01-02T11:30:02","date_gmt":"2011-01-02T17:30:02","guid":{"rendered":"http:\/\/www.lashistorias.com.mx\/?p=7675"},"modified":"2016-10-26T10:21:28","modified_gmt":"2016-10-26T15:21:28","slug":"taller-de-cuento-2011","status":"publish","type":"post","link":"https:\/\/www.lashistorias.com.mx\/index.php\/taller-de-cuento-2011\/","title":{"rendered":"Taller de cuento 2011"},"content":{"rendered":"<p>En 2011, el Taller Integral de Cuento que coordino en la ciudad de M\u00e9xico reanuda sus actividades a partir del s\u00e1bado 8 de enero. Como el taller es permanente, las inscripciones estar\u00e1n abiertas el primer s\u00e1bado de cada mes.<br \/>\n&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Las sesiones se llevar\u00e1n a cabo los s\u00e1bados de 10:00 a 12:00 horas en el primer piso del Caf\u00e9 Lombardi, localizado en Tamaulipas #134-A, colonia Condesa, a un par de cuadras de la librer\u00eda \u00abRosario Castellanos\u00bb del FCE. Aqu\u00ed hay un mapa de la zona:<\/p>\n<div align=center><iframe loading=\"lazy\" width=\"425\" height=\"350\" frameborder=\"0\" scrolling=\"no\" marginheight=\"0\" marginwidth=\"0\" src=\"http:\/\/maps.google.com\/maps?f=q&amp;source=s_q&amp;hl=es&amp;q=Tamaulipas+134,+Hip%C3%B3dromo+Condesa,+Cuauht%C3%A9moc,+Ciudad+de+M%C3%A9xico,+Distrito+Federal,+M%C3%A9xico&amp;aq=&amp;sll=37.0625,-95.677068&amp;sspn=33.764224,56.513672&amp;vpsrc=0&amp;ie=UTF8&amp;geocode=FbYqKAEd3LMW-g&amp;split=0&amp;hq=&amp;hnear=Tamaulipas+134,+Hip%C3%B3dromo+Condesa,+Cuauht%C3%A9moc,+Ciudad+de+M%C3%A9xico,+Distrito+Federal,+M%C3%A9xico&amp;t=m&amp;z=14&amp;ll=19.40959,-99.17546&amp;output=embed\"><\/iframe><br \/><small><a href=\"http:\/\/maps.google.com\/maps?f=q&amp;source=embed&amp;hl=es&amp;q=Tamaulipas+134,+Hip%C3%B3dromo+Condesa,+Cuauht%C3%A9moc,+Ciudad+de+M%C3%A9xico,+Distrito+Federal,+M%C3%A9xico&amp;aq=&amp;sll=37.0625,-95.677068&amp;sspn=33.764224,56.513672&amp;vpsrc=0&amp;ie=UTF8&amp;geocode=FbYqKAEd3LMW-g&amp;split=0&amp;hq=&amp;hnear=Tamaulipas+134,+Hip%C3%B3dromo+Condesa,+Cuauht%C3%A9moc,+Ciudad+de+M%C3%A9xico,+Distrito+Federal,+M%C3%A9xico&amp;t=m&amp;z=14&amp;ll=19.40959,-99.17546\" style=\"color:#0000FF;text-align:left\">Ver mapa m\u00e1s grande<\/a><\/small><\/div>\n<p>El taller se abre para cualquier persona interesada; no hay requisitos previos que cumplir y tampoco una duraci\u00f3n preestablecida: los asistentes pueden quedarse tanto o tan poco tiempo como lo deseen. Las sesiones se centran en la lectura de los textos que los asistentes deseen llevar, que se comentan con miras a discutir sus fortalezas y debilidades, reforzar su t\u00e9cnica, etc\u00e9tera. Al t\u00e9rmino de la discusi\u00f3n se ofrecen lecturas y, ocasionalmente, ejercicios adicionales pensados con base en los textos que se van presentando. En una lista de correo del taller es posible que los asistentes entablen comunicaci\u00f3n entre ellos o bien que utilicen gratuitamente una serie de textos te\u00f3ricos y de apoyo almacenados all\u00ed.<\/p>\n<p>El costo por mes del taller no se eleva y sigue en $500 por persona. Los interesados pueden solicitar m\u00e1s informaci\u00f3n en <a href=\"https:\/\/www.lashistorias.com.mx\/index.php\/contacto\/\">esta p\u00e1gina de contacto<\/a>.<\/p>\n<div align=center><a ref=\"magnificPopup\" href=\"https:\/\/www.lashistorias.com.mx\/wp-content\/uploads\/2011\/01\/Cabinet-of-Curiosities.jpg\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"7684\" data-permalink=\"https:\/\/www.lashistorias.com.mx\/index.php\/taller-de-cuento-2011\/wormiani\/\" data-orig-file=\"https:\/\/www.lashistorias.com.mx\/wp-content\/uploads\/2011\/01\/wormiani.jpg\" data-orig-size=\"500,398\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Frontispicio de Musei Wormiani Historia, cat\u00e1logo de la c\u00e1mara de maravillas de Olaus Wormius\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.lashistorias.com.mx\/wp-content\/uploads\/2011\/01\/wormiani.jpg\" src=\"https:\/\/www.lashistorias.com.mx\/wp-content\/uploads\/2011\/01\/wormiani.jpg\" alt=\"\" title=\"Frontispicio de Musei Wormiani Historia, cat\u00e1logo de la c\u00e1mara de maravillas de Olaus Wormius\" width=\"500\" height=\"398\" class=\"alignnone size-full wp-image-7684\" srcset=\"https:\/\/www.lashistorias.com.mx\/wp-content\/uploads\/2011\/01\/wormiani.jpg 500w, https:\/\/www.lashistorias.com.mx\/wp-content\/uploads\/2011\/01\/wormiani-300x238.jpg 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>En 2011, el Taller Integral de Cuento que coordino en la ciudad de M\u00e9xico reanuda sus actividades a partir del s\u00e1bado 8 de enero. Como el taller es permanente, las inscripciones estar\u00e1n abiertas el primer s\u00e1bado de cada mes. &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Las sesiones se llevar\u00e1n a cabo los s\u00e1bados de 10:00 a 12:00 horas en el primer&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[23,3],"tags":[22,2861,25,2855,816],"class_list":["post-7675","post","type-post","status-publish","format-standard","hentry","category-cursos-y-talleres","category-lo-nuevo","tag-cuento","tag-cursos-y-talleres","tag-escritores","tag-literatura","tag-taller-integral-de-cuento"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/pjEhq-1ZN","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lashistorias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/7675","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lashistorias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lashistorias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lashistorias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lashistorias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=7675"}],"version-history":[{"count":9,"href":"https:\/\/www.lashistorias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/7675\/revisions"}],"predecessor-version":[{"id":12716,"href":"https:\/\/www.lashistorias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/7675\/revisions\/12716"}],"wp:attachment":[{"href":"https:\/\/www.lashistorias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=7675"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lashistorias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=7675"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lashistorias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=7675"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}