{"id":17224,"date":"2025-12-18T01:14:48","date_gmt":"2025-12-18T07:14:48","guid":{"rendered":"https:\/\/www.lashistorias.com.mx\/?p=17224"},"modified":"2025-12-18T01:13:12","modified_gmt":"2025-12-18T07:13:12","slug":"el-bosque-cuento-jorge-cavazos-caballo-negro","status":"publish","type":"post","link":"https:\/\/www.lashistorias.com.mx\/index.php\/el-bosque-cuento-jorge-cavazos-caballo-negro\/","title":{"rendered":"El bosque"},"content":{"rendered":"<p>Jorge Cavazos (Monterrey, 1979) es un artista artista visual mexicano, especializado en ilustraci\u00f3n, dise\u00f1o gr\u00e1fico, pintura y <em>stand up<\/em>. Su obra m\u00e1s conocida, la tira c\u00f3mica <em><a href=\"https:\/\/web.archive.org\/web\/20090323080036\/http:\/\/www.caballonegro.cn\/\">Caballo Negro<\/a><\/em>, mezcla el humor con la exploraci\u00f3n de lo fant\u00e1stico y lo sexual, a trav\u00e9s de una runfla de personajes variopintos. Con este cuento, en el que se encuentran varias leyendas tradicionales mexicanas (en especial de terror) y un humor muy especial, fue finalista del concurso especial por el 20\u00ba aniversario de Las Historias.<\/p>\n<p><a ref=\"magnificPopup\" href=\"https:\/\/www.lashistorias.com.mx\/wp-content\/uploads\/2025\/12\/JorgeCavazos.jpg\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"17225\" data-permalink=\"https:\/\/www.lashistorias.com.mx\/index.php\/el-bosque-cuento-jorge-cavazos-caballo-negro\/jorgecavazos\/\" data-orig-file=\"https:\/\/www.lashistorias.com.mx\/wp-content\/uploads\/2025\/12\/JorgeCavazos.jpg\" data-orig-size=\"640,640\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Jorge Cavazos\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.lashistorias.com.mx\/wp-content\/uploads\/2025\/12\/JorgeCavazos.jpg\" src=\"https:\/\/www.lashistorias.com.mx\/wp-content\/uploads\/2025\/12\/JorgeCavazos.jpg\" alt=\"\" width=\"640\" height=\"640\" class=\"aligncenter size-full wp-image-17225\" srcset=\"https:\/\/www.lashistorias.com.mx\/wp-content\/uploads\/2025\/12\/JorgeCavazos.jpg 640w, https:\/\/www.lashistorias.com.mx\/wp-content\/uploads\/2025\/12\/JorgeCavazos-300x300.jpg 300w, https:\/\/www.lashistorias.com.mx\/wp-content\/uploads\/2025\/12\/JorgeCavazos-150x150.jpg 150w, https:\/\/www.lashistorias.com.mx\/wp-content\/uploads\/2025\/12\/JorgeCavazos-400x400.jpg 400w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><\/p>\n<p><strong>EL BOSQUE<br \/>\nJorge Cavazos<\/strong><\/p>\n<p>Mi abuela era quien insist\u00eda siempre en \u00abjam\u00e1s de los jamases\u00bb ir al bosque. \u00abNo vayas solo. No vayas de noche. No vayas. Ah\u00ed vive una mujer terrible que se roba a los ni\u00f1os traviesos porque sus propios hijos se ahogaron en el r\u00edo y no deja de lamentarse. Los agarra y los mete a su caba\u00f1a, que camina con dos enormes patas de gallo giro. Una vez que se los lleva nadie los vuelve a ver\u00bb. Esa misma historia se repet\u00eda en todas las casas del pueblo, con m\u00e1s o menos las mismas caracter\u00edsticas. A veces era un charro negro quien te llevaba en su caballo, a veces un jinete sin cabeza, a veces un flautista que te hipnotizaba con su melod\u00eda y te lleva a trav\u00e9s de un portal a un lugar del cual no hab\u00eda regreso.<br \/>\n&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;A m\u00ed me emocionaba tanto la idea de ver al lobo, al hombre polilla, a pie grande, a quien fuera de tantos personajes macabros con los que mi abuela y los dem\u00e1s adultos intentaban persuadirnos de evitar entrar en el bosque, que me adentraba (a escondidas) cada vez m\u00e1s y m\u00e1s a la espesura, con tal de ver con mis propios ojos a alguno de esos seres imposibles.<br \/>\n&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Como probablemente adivinan, no soy como los dem\u00e1s ni\u00f1os. Yo \u201cpadec\u00eda\u201d un tipo de \u201csociopat\u00eda\u201d, o eso dijeron en la escuela aquella vez que mandaron llamar a mi abuela porque le machaqu\u00e9 los nudillos al maestro Jim\u00e9nez con un molcajete. Pero esa es otra historia. Lo que le quiero contar es lo de mi muerte.<br \/>\n&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;La primera nevada del a\u00f1o me sorprendi\u00f3 en medio del bosque. Para entonces, yo ya ten\u00eda un par de a\u00f1os escabull\u00e9ndome regularmente, ya hab\u00eda construido un peque\u00f1o refugio, cerca del cual hab\u00eda escondido algunos de mis tesoros m\u00e1s preciados: La pistola de mi abuelo, el meteorito y la mano de mono que mi abuela aseguraba que estaba embrujada y que no quer\u00eda ver \u00abpor nada del mundo\u00bb en la casa.<br \/>\n&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Mir\u00e9 hacia arriba y me ceg\u00f3 una luz blanca, Entrecerr\u00e9 los ojos y pude ver una caba\u00f1a con patas de gallo giro, con una mujer bajo el dintel de la entrada que gritaba \u00ab\u00a1ay, mis hijos!\u00bb. Yo estaba fascinado, los viejos no ment\u00edan, lo que estaba viendo era real. Me acerqu\u00e9 con una sonrisa.<br \/>\n&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;\u2014Te dije que no vinieras\u2014, me dijo mi abuela, con una cara blanca y seria, mojada por los lagrimones que le empapaban la cara.<br \/>\n&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;\u2014\u00bfAbuela? No entiendo. \u00bfT\u00fa eres la dama del bosque?<br \/>\n&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;\u2014S\u00ed es y no lo es\u2014, respondi\u00f3 graznando una figura humana con alas y un pico de lechuza en la cara, que en ese momento bajaba volando hacia m\u00ed.<br \/>\n&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;\u2014\u00bfUsted es el maestro Jim\u00e9nez, verdad? Lo reconozco. \u00bfYa puede mover la mano?<br \/>\n&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Muchas creaturas fant\u00e1sticas y criptidos empezaron a rodearme, reconoc\u00ed a varias personas del pueblo transformadas en entes de las historias que nos contaban. Nunca me hab\u00eda sentido tan feliz.<br \/>\n&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;\u2014\u00bfPor qu\u00e9 me dejan verlos ahora, despu\u00e9s de tanto tiempo?<br \/>\n&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Mi abuela, vestida de blanco y todav\u00eda entre sollozos, se acerc\u00f3 a m\u00ed. Me abraz\u00f3 y me dijo, con una sonrisa: \u00abPorque nos hace falta un fantasma\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El mexicano Jorge Cavazos (1979) re\u00fane el humor y el terror en este relato, finalista del concurso por el 20\u00ba aniversario de Las Historias.<\/p>\n","protected":false},"author":1,"featured_media":17225,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"Con su #cuento \"El bosque\", Jorge Cavazos \u2013artista mexicano, autor del webc\u00f3mic Caballo Negro\u2013 fue finalista en el concurso del 20\u00ba aniversario de Las Historias.","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[4],"tags":[3476,3518,3509,22,3516,2343,198,3517,2855,2291,360],"class_list":["post-17224","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-el-cuento","tag-20-aniversario-de-las-historias","tag-caballo-negro","tag-concurso-de-aniversario-de-las-historias","tag-cuento","tag-el-bosque","tag-el-cuento-del-mes","tag-escritores-mexicanos","tag-jorge-cavazos","tag-literatura","tag-literatura-de-imaginacion","tag-literatura-fantastica"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.lashistorias.com.mx\/wp-content\/uploads\/2025\/12\/JorgeCavazos.jpg","jetpack_shortlink":"https:\/\/wp.me\/pjEhq-4tO","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lashistorias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/17224","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lashistorias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lashistorias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lashistorias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lashistorias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=17224"}],"version-history":[{"count":1,"href":"https:\/\/www.lashistorias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/17224\/revisions"}],"predecessor-version":[{"id":17226,"href":"https:\/\/www.lashistorias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/17224\/revisions\/17226"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lashistorias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/17225"}],"wp:attachment":[{"href":"https:\/\/www.lashistorias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=17224"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lashistorias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=17224"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lashistorias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=17224"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}